{"id":35,"date":"2024-11-06T10:00:51","date_gmt":"2024-11-06T10:00:51","guid":{"rendered":"https:\/\/rbgclinic.com\/?page_id=35"},"modified":"2025-08-06T09:56:24","modified_gmt":"2025-08-06T09:56:24","slug":"politica-cookies","status":"publish","type":"page","link":"https:\/\/rbgclinic.com\/en\/politica-cookies\/","title":{"rendered":"Cookie Policy"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"35\" class=\"elementor elementor-35\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0c5ee e-flex e-con-boxed e-con e-parent\" data-id=\"fb0c5ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-210cb04 elementor-widget elementor-widget-heading\" data-id=\"210cb04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de Cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a233d6 elementor-widget elementor-widget-text-editor\" data-id=\"6a233d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En esta web se utilizan cookies de terceros y propias para conseguir que tengas una mejor experiencia de navegaci\u00f3n, puedas compartir contenido en redes sociales y para que podamos obtener estad\u00edsticas de los usuarios.<\/p><p>Puedes evitar la descarga de cookies a trav\u00e9s de la configuraci\u00f3n de tu navegador, evitando que las cookies se almacenen en su dispositivo.<\/p><p>Como propietario de este sitio web, te comunico que no utilizamos ninguna informaci\u00f3n personal procedente de cookies, tan s\u00f3lo realizamos estad\u00edsticas generales de visitas que no suponen ninguna informaci\u00f3n personal.<\/p><p>Es muy importante que leas la presente pol\u00edtica de cookies y comprendas que, si contin\u00faas navegando, consideraremos que aceptas su uso.<\/p><p>Seg\u00fan los t\u00e9rminos incluidos en el art\u00edculo 22.2 de la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico, si contin\u00faas navegando, estar\u00e1s prestando tu consentimiento para el empleo de los referidos mecanismos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90f253b elementor-widget elementor-widget-text-editor\" data-id=\"90f253b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entidad Responsable<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f1f3ae elementor-widget elementor-widget-text-editor\" data-id=\"8f1f3ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La entidad responsable de la recogida, procesamiento y utilizaci\u00f3n de tus datos personales, en el sentido establecido por la Ley de Protecci\u00f3n de Datos Personales es la p\u00e1gina rbgclinic.com, propiedad de RABAGODON SL \u2013 C. Sevilla, 20, 2\u00aaA, 11402 Jerez de la Frontera, C\u00e1diz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eaa371e elementor-widget elementor-widget-text-editor\" data-id=\"eaa371e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfQu\u00e9 son las cookies?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32d890a elementor-widget elementor-widget-text-editor\" data-id=\"32d890a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las cookies son un conjunto de datos que un servidor deposita en el navegador del usuario para recoger la informaci\u00f3n de registro est\u00e1ndar de Internet y la informaci\u00f3n del comportamiento de los visitantes en un sitio web. Es decir, se trata de peque\u00f1os archivos de texto que quedan almacenados en el disco duro del ordenador y que sirven para identificar al usuario cuando se conecta nuevamente al sitio web. Su objetivo es registrar la visita del usuario y guardar cierta informaci\u00f3n. Su uso es com\u00fan y frecuente en la web ya que permite a las p\u00e1ginas funcionar de manera m\u00e1s eficiente y conseguir una mayor personalizaci\u00f3n y an\u00e1lisis sobre el comportamiento del usuario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8e0bc0 elementor-widget elementor-widget-text-editor\" data-id=\"d8e0bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfQu\u00e9 tipos de cookies existen?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a12774 elementor-widget elementor-widget-text-editor\" data-id=\"4a12774\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las cookies utilizadas en nuestro sitio web, son de sesi\u00f3n y de terceros, y nos permiten almacenar y acceder a informaci\u00f3n relativa al idioma, el tipo de navegador utilizado, y otras caracter\u00edsticas generales predefinidas por el usuario, as\u00ed como, seguir y analizar la actividad que lleva a cabo, con el objeto de introducir mejoras y prestar nuestros servicios de una manera m\u00e1s eficiente y personalizada.<\/p><p>Las cookies, en funci\u00f3n de su permanencia, pueden dividirse en cookies de sesi\u00f3n o permanentes. Las que expiran cuando el usuario cierra el navegador. Las que expiran en funci\u00f3n de cuando se cumpla el objetivo para el que sirven (por ejemplo, para que el usuario se mantenga identificado en los servicios de RBG Clinic) o bien cuando se borran manualmente.<\/p><p>Nombre \/ Tipo \/ Caducidad \/ Finalidad \/ Clase<br \/>__utma \/ De Terceros (Google Analytics) \/ 2 a\u00f1os \/ Se usa para distinguir usuarios y sesiones. \/ No Exenta<br \/>__utmb \/ De Terceros (Google Analytics) \/ 30 minutos \/ Se usa para determinar nuevas sesiones o visitas \/ No Exenta<br \/>__utmc \/ De Terceros (Google Analytics) \/ Al finalizar la sesi\u00f3n Se configura para su uso con Urchin \/ No Exenta<br \/>__utmz \/ De Terceros (Google Analytics) \/ 6 meses \/Almacena el origen o la campa\u00f1a que explica c\u00f3mo el usuario ha llegado hasta la p\u00e1gina web \/ No Exenta<\/p><p>Adicionalmente, en funci\u00f3n de su objetivo, las cookies pueden clasificarse de la siguiente forma:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f84d9d elementor-widget elementor-widget-text-editor\" data-id=\"7f84d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cookies de rendimiento<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5bcc9c elementor-widget elementor-widget-text-editor\" data-id=\"d5bcc9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este tipo de Cookie recuerda sus preferencias para las herramientas que se encuentran en los servicios, por lo que no tiene que volver a configurar el servicio cada vez que usted visita. A modo de ejemplo, en esta tipolog\u00eda se incluyen: Ajustes de volumen de reproductores de v\u00eddeo o sonido. Las velocidades de transmisi\u00f3n de v\u00eddeo que sean compatibles con su navegador. Los objetos guardados en el \u201ccarrito de la compra\u201d en los servicios de e-commerce tales como tiendas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee75368 elementor-widget elementor-widget-text-editor\" data-id=\"ee75368\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cookies de geo-localizaci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f64e2f9 elementor-widget elementor-widget-text-editor\" data-id=\"f64e2f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estas cookies son utilizadas para averiguar en qu\u00e9 pa\u00eds se encuentra cuando se solicita un servicio. Esta cookie es totalmente an\u00f3nima, y s\u00f3lo se utiliza para ayudar a orientar el contenido a su ubicaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5221629 elementor-widget elementor-widget-text-editor\" data-id=\"5221629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cookies de registro<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c92fc2d elementor-widget elementor-widget-text-editor\" data-id=\"c92fc2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las cookies de registro se generan una vez que el usuario se ha registrado o posteriormente ha abierto su sesi\u00f3n, y se utilizan para identificarle en los servicios con los siguientes objetivos:<\/p><p>Mantener al usuario identificado de forma que, si cierra un servicio, el navegador o el ordenador y en otro momento u otro d\u00eda vuelve a entrar en dicho servicio, seguir\u00e1 identificado, facilitando as\u00ed su navegaci\u00f3n sin tener que volver a identificarse. Esta funcionalidad se puede suprimir si el usuario pulsa la funcionalidad [cerrar sesi\u00f3n], de forma que esta cookie se elimina y la pr\u00f3xima vez que entre en el servicio el usuario tendr\u00e1 que iniciar sesi\u00f3n para estar identificado.<\/p><p>Comprobar si el usuario est\u00e1 autorizado para acceder a ciertos servicios, por ejemplo, para participar en un concurso.<\/p><p>Adicionalmente, algunos servicios pueden utilizar conectores con redes sociales tales como Facebook o Twitter. Cuando el usuario se registra en un servicio con credenciales de una red social, autoriza a la red social a guardar una Cookie persistente que recuerda su identidad y le garantiza acceso a los servicios hasta que expira. El usuario puede borrar esta Cookie y revocar el acceso a los servicios mediante redes sociales actualizando sus preferencias en la red social que espec\u00edfica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12eb011 elementor-widget elementor-widget-text-editor\" data-id=\"12eb011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cookies de anal\u00edticas<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6a234f elementor-widget elementor-widget-text-editor\" data-id=\"a6a234f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cada vez que un usuario visita un servicio, una herramienta de un proveedor externo genera una cookie anal\u00edtica en el ordenador del usuario. Esta cookie que s\u00f3lo se genera en la visita, servir\u00e1 en pr\u00f3ximas visitas a los servicios de RBG Clinic para identificar de forma an\u00f3nima al visitante. Los objetivos principales que se persiguen son:<\/p><p>Permitir la identificaci\u00f3n an\u00f3nima de los usuarios navegantes a trav\u00e9s de la cookie (identifica navegadores y dispositivos, no personas) y por lo tanto la contabilizaci\u00f3n aproximada del n\u00famero de visitantes y su tendencia en el tiempo.<br \/>Identificar de forma an\u00f3nima los contenidos m\u00e1s visitados y por lo tanto m\u00e1s atractivos para los usuarios Saber si el usuario que est\u00e1 accediendo es nuevo o repite visita.<\/p><p>Importante: Salvo que el usuario decida registrarse en un servicio de RBG Clinic, la cookie nunca ir\u00e1 asociada a ning\u00fan dato de car\u00e1cter personal que pueda identificarle. Dichas cookies s\u00f3lo ser\u00e1n utilizadas con prop\u00f3sitos estad\u00edsticos que ayuden a la optimizaci\u00f3n de la experiencia de los usuarios en el sitio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-944fa64 elementor-widget elementor-widget-text-editor\" data-id=\"944fa64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cookies de publicidad<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380e161 elementor-widget elementor-widget-text-editor\" data-id=\"380e161\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este tipo de cookies permiten ampliar la informaci\u00f3n de los anuncios mostrados a cada usuario an\u00f3nimo en los servicios de RBG Clinic. Entre otros, se almacena la duraci\u00f3n o frecuencia de visualizaci\u00f3n de posiciones publicitarias, la interacci\u00f3n con las mismas, o los patrones de navegaci\u00f3n y\/o comportamientos del usuario ya que ayudan a conformar un perfil de inter\u00e9s publicitario. De este modo, permiten ofrecer publicidad af\u00edn a los intereses del usuario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bba06e2 elementor-widget elementor-widget-text-editor\" data-id=\"bba06e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cookies publicitarias de terceros<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aa4115 elementor-widget elementor-widget-text-editor\" data-id=\"2aa4115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adem\u00e1s de la publicidad gestionada por las webs de RBG Clinic en sus servicios, las webs de RBG Clinic ofrecen a sus anunciantes la opci\u00f3n de servir anuncios a trav\u00e9s de terceros (\u201cAd-Servers\u201d). De este modo, estos terceros pueden almacenar cookies enviadas desde los servicios de RBG Clinic procedentes de los navegadores de los usuarios, as\u00ed como acceder a los datos que en ellas se guardan.<\/p><p>Las empresas que generan estas cookies tienen sus propias pol\u00edticas de privacidad. En la actualidad, las webs de RBG Clinic utilizan la plataforma Doubleclick (Google) para gestionar estos servicios. Para m\u00e1s informaci\u00f3n, acuda a<\/p><p>http:\/\/www.google.es\/policies\/privacy\/ads\/#toc-doubleclick y a http:\/\/www.google.es\/policies\/privacy\/ads\/.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0aea84 elementor-widget elementor-widget-text-editor\" data-id=\"b0aea84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfC\u00f3mo puedo deshabilitar las cookies en mi navegador?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93c6d81 elementor-widget elementor-widget-text-editor\" data-id=\"93c6d81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se pueden configurar los diferentes navegadores para avisar al usuario de la recepci\u00f3n de cookies y, si se desea, impedir su instalaci\u00f3n en el equipo. Asimismo, el usuario puede revisar en su navegador qu\u00e9 cookies tiene instaladas y cu\u00e1l es el plazo de caducidad de las mismas, pudiendo eliminarlas.<\/p><p>Para ampliar esta informaci\u00f3n consulte las instrucciones y manuales de su navegador:<\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Google Chrome: https:\/\/support.google.com\/chrome\/answer\/95647?hl=es<\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Internet Explorer: http:\/\/windows.microsoft.com\/es-es\/windows-vista\/cookies-frequently-asked-questions<\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Mozilla Firefox: http:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-que-los-sitios-we<\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Safari: http:\/\/www.apple.com\/es\/privacy\/use-of-cookies\/<\/p><p>Para m\u00e1s informaci\u00f3n sobre la administraci\u00f3n de las cookies en Opera: http:\/\/help.opera.com\/Windows\/11.50\/es-ES\/cookies.html<\/p><p>Si desea dejar de ser seguido por Google Analytics visite: http:\/\/tools.google.com\/dlpage\/gaoptout<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d0df95 elementor-widget elementor-widget-text-editor\" data-id=\"8d0df95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para saber m\u00e1s sobre las cookies<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e481a7f elementor-widget elementor-widget-text-editor\" data-id=\"e481a7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Puede obtener m\u00e1s informaci\u00f3n sobre la publicidad online basada en el comportamiento y la privacidad online en el siguiente enlace: http:\/\/www.youronlinechoices.com\/es\/<\/p><p>Protecci\u00f3n de datos de Google Analytics: http:\/\/www.google.com\/analytics\/learn\/privacy.html<\/p><p>C\u00f3mo usa Google Analytics las cookies: https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage?hl=es#analyticsjs<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64e61a1 elementor-widget elementor-widget-text-editor\" data-id=\"64e61a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Actualizaciones y cambios en la pol\u00edtica de privacidad\/cookies<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b1df61 elementor-widget elementor-widget-text-editor\" data-id=\"8b1df61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las webs de RBG Clinic pueden modificar esta Pol\u00edtica de Cookies en funci\u00f3n de exigencias legislativas, reglamentarias, o con la finalidad de adaptar dicha pol\u00edtica a las instrucciones dictadas por la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, por ello se aconseja a los usuarios que la visiten peri\u00f3dicamente.<\/p><p>Cuando se produzcan cambios significativos en esta Pol\u00edtica de Cookies, estos se comunicar\u00e1n a los usuarios bien mediante la web o a trav\u00e9s de correo electr\u00f3nico a los usuarios registrados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Cookies En esta web se utilizan cookies de terceros y propias para conseguir que tengas una mejor experiencia de navegaci\u00f3n, puedas compartir contenido en redes sociales y para que podamos obtener estad\u00edsticas de los usuarios. Puedes evitar la descarga de cookies a trav\u00e9s de la configuraci\u00f3n de tu navegador, evitando que las cookies [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-35","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de cookies | RBG Clinic \u2014 Dentista en Jerez de la Frontera<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de cookies | RBG Clinic \u2014 Dentista en Jerez de la Frontera\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de Cookies En esta web se utilizan cookies de terceros y propias para conseguir que tengas una mejor experiencia de navegaci\u00f3n, puedas compartir contenido en redes sociales y para que podamos obtener estad\u00edsticas de los usuarios. Puedes evitar la descarga de cookies a trav\u00e9s de la configuraci\u00f3n de tu navegador, evitando que las cookies [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rbgclinic.com\/en\/politica-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"RBG Clinic \u2014 Dentista en Jerez de la Frontera\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RbgclinicDrRabago\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T09:56:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rbgclinic.com\/wp-content\/uploads\/2025\/04\/rbg-clinica-dental-jerez.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@rbgclinic\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/politica-cookies\\\/\",\"url\":\"https:\\\/\\\/rbgclinic.com\\\/politica-cookies\\\/\",\"name\":\"Pol\u00edtica de cookies | RBG Clinic \u2014 Dentista en Jerez de la Frontera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/#website\"},\"datePublished\":\"2024-11-06T10:00:51+00:00\",\"dateModified\":\"2025-08-06T09:56:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/politica-cookies\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rbgclinic.com\\\/politica-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/politica-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/rbgclinic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/#website\",\"url\":\"https:\\\/\\\/rbgclinic.com\\\/\",\"name\":\"C\u00ednica dental RBG Clinic Jerez\",\"description\":\"Cl\u00ednica dental en Jerez de la Frontera. Especialistas en implantes, ortodoncia y est\u00e9tica dental.\",\"publisher\":{\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/#organization\"},\"alternateName\":\"Cl\u00ednica dental RBG Clinic Jerez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rbgclinic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/#organization\",\"name\":\"RBG Clinic | Cl\u00ednica Dental en Jerez\",\"alternateName\":\"Cl\u00ednica dental RBG Clinic Jerez\",\"url\":\"https:\\\/\\\/rbgclinic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rbgclinic.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/rbg-clinica-dental-jerez.webp\",\"contentUrl\":\"https:\\\/\\\/rbgclinic.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/rbg-clinica-dental-jerez.webp\",\"width\":1080,\"height\":1080,\"caption\":\"RBG Clinic | Cl\u00ednica Dental en Jerez\"},\"image\":{\"@id\":\"https:\\\/\\\/rbgclinic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RbgclinicDrRabago\",\"https:\\\/\\\/x.com\\\/rbgclinic\",\"https:\\\/\\\/www.instagram.com\\\/rbgclinic\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ClinicaDentalRBGClinicJerez\\\/\",\"https:\\\/\\\/www.doctoralia.es\\\/clinicas\\\/rbg-instituto-de-odontologia-y-cirugia-oral-dr-rabago\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de cookies | RBG Clinic \u2014 Dentista en Jerez de la Frontera","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_GB","og_type":"article","og_title":"Pol\u00edtica de cookies | RBG Clinic \u2014 Dentista en Jerez de la Frontera","og_description":"Pol\u00edtica de Cookies En esta web se utilizan cookies de terceros y propias para conseguir que tengas una mejor experiencia de navegaci\u00f3n, puedas compartir contenido en redes sociales y para que podamos obtener estad\u00edsticas de los usuarios. Puedes evitar la descarga de cookies a trav\u00e9s de la configuraci\u00f3n de tu navegador, evitando que las cookies [&hellip;]","og_url":"https:\/\/rbgclinic.com\/en\/politica-cookies\/","og_site_name":"RBG Clinic \u2014 Dentista en Jerez de la Frontera","article_publisher":"https:\/\/www.facebook.com\/RbgclinicDrRabago","article_modified_time":"2025-08-06T09:56:24+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/rbgclinic.com\/wp-content\/uploads\/2025\/04\/rbg-clinica-dental-jerez.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@rbgclinic","twitter_misc":{"Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rbgclinic.com\/politica-cookies\/","url":"https:\/\/rbgclinic.com\/politica-cookies\/","name":"Pol\u00edtica de cookies | RBG Clinic \u2014 Dentista en Jerez de la Frontera","isPartOf":{"@id":"https:\/\/rbgclinic.com\/#website"},"datePublished":"2024-11-06T10:00:51+00:00","dateModified":"2025-08-06T09:56:24+00:00","breadcrumb":{"@id":"https:\/\/rbgclinic.com\/politica-cookies\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rbgclinic.com\/politica-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rbgclinic.com\/politica-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/rbgclinic.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies"}]},{"@type":"WebSite","@id":"https:\/\/rbgclinic.com\/#website","url":"https:\/\/rbgclinic.com\/","name":"RBG Clinic Jerez dental clinic","description":"Dental clinic in Jerez de la Frontera. Specialists in implants, orthodontics and cosmetic dentistry.","publisher":{"@id":"https:\/\/rbgclinic.com\/#organization"},"alternateName":"Cl\u00ednica dental RBG Clinic Jerez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rbgclinic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/rbgclinic.com\/#organization","name":"RBG Clinic | Dental Clinic in Jerez","alternateName":"Cl\u00ednica dental RBG Clinic Jerez","url":"https:\/\/rbgclinic.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/rbgclinic.com\/#\/schema\/logo\/image\/","url":"https:\/\/rbgclinic.com\/wp-content\/uploads\/2025\/04\/rbg-clinica-dental-jerez.webp","contentUrl":"https:\/\/rbgclinic.com\/wp-content\/uploads\/2025\/04\/rbg-clinica-dental-jerez.webp","width":1080,"height":1080,"caption":"RBG Clinic | Cl\u00ednica Dental en Jerez"},"image":{"@id":"https:\/\/rbgclinic.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RbgclinicDrRabago","https:\/\/x.com\/rbgclinic","https:\/\/www.instagram.com\/rbgclinic\/","https:\/\/www.youtube.com\/@ClinicaDentalRBGClinicJerez\/","https:\/\/www.doctoralia.es\/clinicas\/rbg-instituto-de-odontologia-y-cirugia-oral-dr-rabago"]}]}},"_links":{"self":[{"href":"https:\/\/rbgclinic.com\/en\/wp-json\/wp\/v2\/pages\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rbgclinic.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rbgclinic.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rbgclinic.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rbgclinic.com\/en\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":0,"href":"https:\/\/rbgclinic.com\/en\/wp-json\/wp\/v2\/pages\/35\/revisions"}],"wp:attachment":[{"href":"https:\/\/rbgclinic.com\/en\/wp-json\/wp\/v2\/media?parent=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}